{"id":1791,"date":"2012-09-20T13:14:29","date_gmt":"2012-09-20T16:14:29","guid":{"rendered":"http:\/\/www.cna.org.ar\/?p=1791"},"modified":"2012-09-20T13:14:29","modified_gmt":"2012-09-20T16:14:29","slug":"el-juez-daniel-rafecas-presento-su-libro-historia-de-la-solucion-final","status":"publish","type":"post","link":"https:\/\/cna.org.ar\/index.php\/2012\/09\/20\/el-juez-daniel-rafecas-presento-su-libro-historia-de-la-solucion-final\/","title":{"rendered":"El juez Daniel Rafecas present\u00f3 su libro \u201cHistoria de la Soluci\u00f3n Final\u201d"},"content":{"rendered":"<p>Es importante remarcar que la presente actividad fue organizada en conjunto con la DAIA (Delegaci\u00f3n Israelita de Argentina \u2013 Filial C\u00f3rdoba) y el Consejo Nacional Armenio de Sudam\u00e9rica \u2013 C\u00f3rdoba. A lo largo de la presentaci\u00f3n el Dr. Rafecas se refiri\u00f3 a las causas que desembocaron a la Sho\u00e1 (Holocausto) he hizo referencia al Genocidio de los Armenios y en particular al cap\u00edtulo en su obra que hace hincapi\u00e9 a las vinculaciones de los cr\u00edmenes nazis contra el pueblo jud\u00edo con respecto al Genocidio Armenio perpetrado por los turcos a principios del siglo XX.<br \/>\nAs\u00ed mismo, tanto los presentadores del libro como la DAIA y en particular el Dr. Rafeas agradecieron expresamente al Consejo Nacional Armenio por el auspicio y apoyo para la realizaci\u00f3n de esta importante actividad.<\/p>\n<p><span style=\"color: #ff6600;\">.<\/span><br \/>\nUna vez finalizada la presentaci\u00f3n formal, se abri\u00f3 un espacio para que los presentes formulen preguntas en relaci\u00f3n a la obra. Finalmente el director del CNA, Lucas Koussikian, hico entrega de un presente al Dr. Rafecas por su esfuerzo y constante trabajo por los Derechos Humanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"http:\/\/www.cna.org.ar\/wp-content\/uploads\/2012\/09\/Rafecas1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1798\" title=\"Rafecas\" src=\"http:\/\/www.cna.org.ar\/wp-content\/uploads\/2012\/09\/Rafecas1-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" \/><\/a>Importante actividad en el marco de la Feria del Libro \u2013 C\u00f3rdoba 2012<br \/>\n&#8211;<br \/>\nEl pasado mi\u00e9rcoles 12 de setiembre en el \u00e1mbito de la Feria C\u00f3rdoba 2012 tuvo lugar la presentaci\u00f3n de la importante obra del juez Daniel Rafecas.  La presentaci\u00f3n estuvo a cargo de la Fiscal Federal Graciela L\u00f3pez de Filo\u00f1uk y del periodista de la Voz del Interior Sergio Suppo. A su vez estuvieron presentes importantes personalidades del \u00e1mbito pol\u00edtico y judicial. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1791","post","type-post","status-publish","format-standard","hentry","category-actividades"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/posts\/1791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/comments?post=1791"}],"version-history":[{"count":0,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/posts\/1791\/revisions"}],"wp:attachment":[{"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/media?parent=1791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/categories?post=1791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/tags?post=1791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}