{"id":2006,"date":"2013-03-08T16:16:54","date_gmt":"2013-03-08T19:16:54","guid":{"rendered":"http:\/\/www.cna.org.ar\/?p=2006"},"modified":"2016-02-18T15:10:16","modified_gmt":"2016-02-18T15:10:16","slug":"azerbaiyan-otra-forma-de-negacionismo","status":"publish","type":"post","link":"https:\/\/cna.org.ar\/index.php\/2013\/03\/08\/azerbaiyan-otra-forma-de-negacionismo\/","title":{"rendered":"Azerbaiy\u00e1n: otra forma de negacionismo"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/www.cna.org.ar\/wp-content\/uploads\/2013\/03\/com-sumg-nota.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-2125\" src=\"https:\/\/i0.wp.com\/www.cna.org.ar\/wp-content\/uploads\/2013\/03\/com-sumg-nota.jpg?resize=597%2C353\" alt=\"\" width=\"597\" height=\"353\" \/><\/a><\/p>\n<p>La Embajada de Azerbaiy\u00e1n en la Argentina ha expresado a trav\u00e9s de una nota, utilizando el derecho a r\u00e9plica, su posici\u00f3n sobre la conmemoraci\u00f3n de la colectividad armenia del vig\u00e9simoquinto aniversario del pogromo de Sumgait. Este hecho doloroso fue la punta de lanza de otros ataques que provocaron cientos de muertos, miles de heridos, y cientos de miles de desplazados de todo Azerbaiy\u00e1n. Desde el Consejo Nacional Armenio de Sudam\u00e9rica, creemos que es importante destacar algunos de sus planteos que resultan inaceptables para \u00a0cualquier Estado u organizaci\u00f3n social que tenga entre sus premisas la defensa de los Derechos Humanos.<\/p>\n<p>La nota, adem\u00e1s de plantear una serie de vaguedades e imprecisiones en la relaci\u00f3n hist\u00f3rica de Armenia y Azerbaiy\u00e1n, cuando no mentiras deliberadas, destaca la responsabilidad de los armenios en el pogromo de Sumgait. Para el estado azer\u00ed, se trat\u00f3 de un autoatentado necesario para justificar las incursiones militares en Nagorno-Karabagh. El procedimiento de culpar a las v\u00edctimas es una de las formas habituales del negacionismo, por lo que no deber\u00eda pasar desapercibido para ning\u00fan defensor de los Derechos Humanos. Ser\u00eda inaceptable que Alemania culpara al pueblo jud\u00edo por la Sho\u00e1, como resultar\u00eda horroroso en nuestro pa\u00eds que el Estado afirmara hoy que los 30.000 desaparecidos se autoexiliaron.<\/p>\n<p>No es sorprendente este tipo de afirmaciones por parte de la Rep\u00fablica de Azerbaiy\u00e1n. Los Derechos Humanos distan de ser pol\u00edtica de Estado, como lo son en la Argentina. Los presos de conciencia, en especial periodistas y activistas pol\u00edticos, son moneda corriente. Por citar hechos recientes, desde marzo de 2011, Amnist\u00eda Internacional condena la violencia ejercida desde el gobierno de Aliyev frente a manifestaciones p\u00fablicas opositoras. En mayo de 2012, el Parlamento Europeo conden\u00f3 a trav\u00e9s de la resoluci\u00f3n 2012\/2654(RSP) las sistem\u00e1ticas violaciones a los Derechos Humanos en ese pa\u00eds. Y en febrero de este a\u00f1o fue sentenciado a ocho a\u00f1os de prisi\u00f3n Bahtyar Mamedov, defensor de los habitantes de Bak\u00fa que fueron despojados de sus hogares para construir una autopista. En muchos casos, los funcionarios azer\u00edes suelen caracterizar a los opositores como agentes armenios.<\/p>\n<p>Asimismo, la Embajada de Azerbaiy\u00e1n en la Argentina afirma que su objetivo es la paz justa y duradera en la regi\u00f3n. Esta afirmaci\u00f3n, lamentablemente, no se corresponde con la verdad. En el discurso de cierre de la Conferencia \u201cPrograma estatal de desarrollo socio econ\u00f3mico de distritos del 2009-2013\u201d, Ilham Aliyev afirm\u00f3 de manera p\u00fablica e inequ\u00edvoca: \u201cnuestros enemigos principales son los armenios de todo el mundo y los pol\u00edticos hip\u00f3critas y corruptos bajo su control\u201d. Tambi\u00e9n se podr\u00eda colegir que en el caso argentino, siguiendo el razonamiento, ser\u00edan todos los representantes del Poder Ejecutivo, Legislativo y Judicial, ya que en esas tres instancias funcionarios argentinos han abogado por el pueblo armenio.<\/p>\n<p>Este tipo de afirmaciones, que son cotidianas entre los funcionarios, el partido de gobierno y los medios oficialistas, no son la \u00fanica forma de la Rep\u00fablica de Azerbaiy\u00e1n de alentar el conflicto con Armenia. En agosto de 2012,el soldado Ramil Safarov retorn\u00f3 a su pa\u00eds, despu\u00e9s de haber estado preso en Hungr\u00eda, condenado a cadena perpetua por haber decapitado con un hacha al militar armenio Gurgen Markarian mientras dorm\u00eda, durante un curso de la OTAN en Budapest. Ilham Aliyev no s\u00f3lo lo indult\u00f3, sino que lo ascendi\u00f3 de rango, le obsequi\u00f3 una vivienda y el salario de los ocho a\u00f1os que hab\u00eda cumplido en prisi\u00f3n, d\u00e1ndole rango de h\u00e9roe nacional y ejemplo para la sociedad azerbaiyana. Al mismo tiempo, la violaci\u00f3n del cese al fuego en la frontera con Nagorno Karabagh es permanente. Su v\u00edctima m\u00e1s reciente es Gor Kazarouian, asesinado el pasado 19 de febrero.<\/p>\n<p>Desde el Consejo Nacional Armenio de Sudam\u00e9rica, entendemos que la experiencia hist\u00f3rica demuestra que los pueblos pueden avanzar en materia de Derechos Humanos cuando son capaces de reconocer los horrores que han vivido. El caso de la Rep\u00fablica de Azerbaiy\u00e1n no es la excepci\u00f3n. La negaci\u00f3n del horror de hace 25 a\u00f1os coexiste con las violaciones sistem\u00e1ticas a los derechos de sus ciudadanos y la b\u00fasqueda de la escalada b\u00e9lica. Cuando los gobernantes plantean que una porci\u00f3n delimitada de la sociedad es la causa de los problemas de su naci\u00f3n , las consecuencias son siempre tr\u00e1gicas.<\/p>\n<p>Buenos aires, 8 de marzo de 2013<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Embajada de Azerbaiy\u00e1n en la Argentina ha expresado a trav\u00e9s de una nota, utilizando el derecho a r\u00e9plica, su posici\u00f3n sobre la conmemoraci\u00f3n de la colectividad armenia del vig\u00e9simoquinto aniversario del pogromo de Sumgait. Este hecho doloroso fue la punta de lanza de otros ataques que provocaron cientos de muertos, miles de heridos, y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[24,16,25,45,46,47,18,12,48,49,50,51],"class_list":["post-2006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicados","tag-argentina","tag-armenia-2","tag-armenios","tag-azerbaidjan","tag-azerbaijan","tag-azerbaiyan","tag-derechos-humanos","tag-negacionismo","tag-sumgait","tag-sumgayit","tag-sumqait","tag-sumqayit"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/cna.org.ar\/wp-content\/uploads\/2013\/03\/com-sumg-nota1.jpg?fit=995%2C589&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/posts\/2006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2006"}],"version-history":[{"count":1,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/posts\/2006\/revisions"}],"predecessor-version":[{"id":4395,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/posts\/2006\/revisions\/4395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/media\/4394"}],"wp:attachment":[{"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cna.org.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}